{"id":7822,"date":"2026-02-04T22:52:39","date_gmt":"2026-02-04T21:52:39","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=7822"},"modified":"2026-02-04T23:30:02","modified_gmt":"2026-02-04T22:30:02","slug":"ex-uhc-handballerinnen-bei-noen-sportlerwahl","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/ex-uhc-handballerinnen-bei-noen-sportlerwahl\/","title":{"rendered":"Ex-UHC-HandballerInnen bei N\u00d6N-Sportlerwahl!"},"content":{"rendered":"\n<p>Anfang M\u00e4rz werden die Gewinnerinnen und Gewinner der N\u00d6N-Sportlerwahl bekanntgegeben, dieses Jahr findet man unter den Nominierten auch wieder Sportlerinnen mit UHC-Wurzeln: Luna und Sina Hahn!<\/p>\n\n\n\n<p>Luna \u00fcbersiedelte im vergangenen Sommer ins Leistungszentrum S\u00fcdstadt und zu Hypo N\u00d6. Davor konnte die &#8211; zu dem Zeitpunkt &#8211; noch 14-J\u00e4hrige bei der U17-EM \u00fcberzeugen, in mehreren Spielen war sie die beste rot-wei\u00df-rote Werferin.<\/p>\n\n\n\n<p>Sina wechselte im Sommer 2023 ins Leistungszentrum nach St. P\u00f6lten, etablierte sich dort schnell in der WHA-Meisterliga-Mannschaft. Bald folgten die ersten Auszeichnungen zum &#8220;Player of the Match&#8221;, zudem durfte sie f\u00fcr das U19-Nationalteam auflaufen.<\/p>\n\n\n\n<p>Unter den m\u00e4nnlichen Nominierten ist auch Leonhard Prager. Er war vor Jahren noch als Handballer beim UHC aktiv, ist nun aufgrund seiner Leistungen im Racketlon nominiert.<\/p>\n\n\n\n<p>Unter folgendem Link kannst Du 1x pro Stunde abstimmen, das Voting l\u00e4uft bis 27. Februar, 12:00 Uhr:<\/p>\n\n\n\n<p><a href=\"https:\/\/m.noen.at\/sportlerwahl\/noen-sportlerwahl-2025-das-sind-die-nominierten-im-bezirk-gaenserndorf-507580911?fbclid=IwY2xjawPwmeFleHRuA2FlbQIxMABzcnRjBmFwcF9pZBAyMjIwMzkxNzg4MjAwODkyAAEeFCUI1-ysnd1Xpyb3b32wUe8vGYdcSgIkuP0BrGBJPSvV0ILCct2RQfR7-0E_aem__1HPeyXEthA59R4RuAQXMg#507580911-6753149,507580911-67tkbhep53ap14c9-0\">N\u00d6N-Sportlerwahl 2025 &#8211; Das sind die Nominierten im Bezirk G\u00e4nserndorf &#8211; N\u00d6N.at<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anfang M\u00e4rz werden die Gewinnerinnen und Gewinner der N\u00d6N-Sportlerwahl bekanntgegeben, dieses Jahr findet man unter den Nominierten auch wieder Sportlerinnen mit UHC-Wurzeln: Luna und Sina Hahn! Luna \u00fcbersiedelte im vergangenen Sommer ins Leistungszentrum S\u00fcdstadt und zu Hypo N\u00d6. Davor konnte die &#8211; zu dem Zeitpunkt &#8211; noch 14-J\u00e4hrige bei der U17-EM \u00fcberzeugen, in mehreren Spielen &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/ex-uhc-handballerinnen-bei-noen-sportlerwahl\/\"> <span class=\"screen-reader-text\">Ex-UHC-HandballerInnen bei N\u00d6N-Sportlerwahl!<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":7823,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-7822","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/7822","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=7822"}],"version-history":[{"count":2,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/7822\/revisions"}],"predecessor-version":[{"id":7826,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/7822\/revisions\/7826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/7823"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=7822"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=7822"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=7822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}