{"id":7614,"date":"2025-10-18T18:39:00","date_gmt":"2025-10-18T16:39:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=7614"},"modified":"2025-11-02T15:40:53","modified_gmt":"2025-11-02T14:40:53","slug":"spannender-schlagabtausch-knappe-niederlage-fuer-u16-maedels","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/spannender-schlagabtausch-knappe-niederlage-fuer-u16-maedels\/","title":{"rendered":"Spannender Schlagabtausch, knappe Niederlage f\u00fcr U16 M\u00e4dels"},"content":{"rendered":"\n<p><a><\/a>Im spannenden und \u00fcber weite Strecken ausgeglichenen Spiel pr\u00e4sentierte sich unser Team k\u00e4mpferisch und hielt das Tempo stets hoch.<\/p>\n\n\n\n<p>In der ersten Halbzeit entwickelte sich ein offener Schlagabtausch mit Treffern auf beiden Seiten \u2013 keine Mannschaft konnte sich absetzen.<\/p>\n\n\n\n<p>Verletzungsbedingt fehlte Torfrau Lisa Pasi, die von Anastasija Dujkovic vertreten wurde. Diese zeigte in ihrem ersten Spiel mehrere sehenswerte Paraden und st\u00e4rkte dem Team in wichtigen Momenten den R\u00fccken.<\/p>\n\n\n\n<p>Auch die zweite Halbzeit blieb offen mit h\u00e4ufigen F\u00fchrungswechseln, ehe G\u00e4nserndorf in den letzten Minuten einige R\u00fcckschl\u00e4ge hinnehmen musste. Dennoch erspielte sich das Team weitere gute Chancen und gestaltete das Match bis zum Schluss offen.<\/p>\n\n\n\n<p>Am Ende stand eine knappe 26:27-Niederlage, aber das Team kann mit seiner Leistung, dem Einsatz und dem Kampfgeist sehr zufrieden sein. Das Auftreten macht Hoffnung f\u00fcr die n\u00e4chsten Begegnungen.<\/p>\n\n\n\n<p>Dujkovic A., Zenelaj A., Guger M., Jelemensky S., G\u00f6schl M., Miler A. 7, Fuchs H., Prager M. 2, Schmid N. 7, Miler L. 9, Schlederer N. 1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im spannenden und \u00fcber weite Strecken ausgeglichenen Spiel pr\u00e4sentierte sich unser Team k\u00e4mpferisch und hielt das Tempo stets hoch. In der ersten Halbzeit entwickelte sich ein offener Schlagabtausch mit Treffern auf beiden Seiten \u2013 keine Mannschaft konnte sich absetzen. Verletzungsbedingt fehlte Torfrau Lisa Pasi, die von Anastasija Dujkovic vertreten wurde. Diese zeigte in ihrem ersten &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/spannender-schlagabtausch-knappe-niederlage-fuer-u16-maedels\/\"> <span class=\"screen-reader-text\">Spannender Schlagabtausch, knappe Niederlage f\u00fcr U16 M\u00e4dels<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":7615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-7614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/7614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=7614"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/7614\/revisions"}],"predecessor-version":[{"id":7616,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/7614\/revisions\/7616"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/7615"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=7614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=7614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=7614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}