{"id":6878,"date":"2025-02-23T15:59:00","date_gmt":"2025-02-23T14:59:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=6878"},"modified":"2025-02-28T00:00:55","modified_gmt":"2025-02-27T23:00:55","slug":"u16w-2-elite-cup-spiele-ein-wechselbad-der-gefuehle","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u16w-2-elite-cup-spiele-ein-wechselbad-der-gefuehle\/","title":{"rendered":"U16W: 2 Elite-Cup-Spiele &#8211; ein Wechselbad der Gef\u00fchle"},"content":{"rendered":"\n<p>Gegen die W\u00f6lfe schaffte es das Team leider nicht, an die starken Leistungen in Graz und Atzgersdorf anzuschlie\u00dfen.<\/p>\n\n\n\n<p>In der Wr. Stadthalle musste man sich dem mit viel Leidenschaft auftreteten Team der W\u00f6lfe Wien mit 37:39 geschlagen geben. 22 Gegentore in H\u00e4lfte 1 waren zuviel.<\/p>\n\n\n\n<p>Umso <a><\/a>mehr wollten die M\u00e4dls am Tag darauf zeigen, dass sie es besser k\u00f6nnen. Das Duell mit St.P\u00f6lten gestaltete sich auch von Beginn an ganz anders. Beide Teams trafen ja in den letzten Jahren immer wieder aufeinander.<\/p>\n\n\n\n<p>Diesmal schaffte es G\u00e4nserndorf, mit mehr Willen und Einsatz (nach 0:2) bis zur Pause mit 15:11 in F\u00fchrung zu gehen. Die Abwehr rund um Torfrau Lisa Pasi pr\u00e4sentierte sich ganz anders als noch am Vortag.<\/p>\n\n\n\n<p>Nach Seitenwechsel schaffte man es zwar nicht, das \u00dcberzahlspiel zu nutzen. Trotzdem konnte man die F\u00fchrung ausbauen. Indira Quintana setzte ein Zeichen und spielte trotz Handverletzung bis 10 Minuten vor Schluss, dann musste sie w.o. geben. Eine genaue Diagnose steht noch aus.<\/p>\n\n\n\n<p>Mit dem 23:18-Erfolg bringt sich das u16-Team selbst zur\u00fcck in den Kampf um die Teilnahme am Final4.<\/p>\n\n\n\n<p>W\u00f6lfe Wien &#8211; UHC Raiffeisenbank G\u00e4nserndorf 39:37 (22:16)<\/p>\n\n\n\n<p>L.Pasi; A.Deubner 3, D.Schlederer, L.Ellinger 4, I.Quintana 7\/1, L.Hahn 15\/4, H.Fuchs 2, J.Schodl, N.Schmid 6, S.Jelemensky, L.Scheidl 1<\/p>\n\n\n\n<p>UHC Raiffeisenbank G\u00e4nserndorf &#8211; St.P\u00f6lten 23:18 (15:11)<\/p>\n\n\n\n<p>L.Pasi; A.Deubner, L.Ellinger 2, I.Quintana 3, L.Hahn 11\/1, H.Fuchs 2, J.Schodl, N.Schmid 4, S.Jelemensky, L.Scheidl 1<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gegen die W\u00f6lfe schaffte es das Team leider nicht, an die starken Leistungen in Graz und Atzgersdorf anzuschlie\u00dfen. In der Wr. Stadthalle musste man sich dem mit viel Leidenschaft auftreteten Team der W\u00f6lfe Wien mit 37:39 geschlagen geben. 22 Gegentore in H\u00e4lfte 1 waren zuviel. Umso mehr wollten die M\u00e4dls am Tag darauf zeigen, dass &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u16w-2-elite-cup-spiele-ein-wechselbad-der-gefuehle\/\"> <span class=\"screen-reader-text\">U16W: 2 Elite-Cup-Spiele &#8211; ein Wechselbad der Gef\u00fchle<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":6879,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-6878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=6878"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6878\/revisions"}],"predecessor-version":[{"id":6880,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6878\/revisions\/6880"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/6879"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=6878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=6878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=6878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}