{"id":6691,"date":"2024-11-24T19:48:00","date_gmt":"2024-11-24T18:48:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=6691"},"modified":"2024-12-05T23:50:44","modified_gmt":"2024-12-05T22:50:44","slug":"maenner-kantersieg-mit-wermutstropfen","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/maenner-kantersieg-mit-wermutstropfen\/","title":{"rendered":"M\u00e4nner: Kantersieg mit Wermutstropfen"},"content":{"rendered":"\n<p>Dieses Mal empfing unsere Herrenmannschaft das #1 Team HSV aus Wien. Da die G\u00e4ste stark ersatzgeschw\u00e4cht anreisten ging unser Team als klarer Favorit in die Partie.<\/p>\n\n\n\n<p>Zu Beginn war allerdings alles ausgeglichen. Offensiv funktionierte vieles, defensiv eher wenig, so stand es nach 13 gespielten Minuten 8:8. Danach konnte man aber dank einer verbesserten Abwehrleistung und einem starken R\u00fcckhalt Peter Perdoch bis zur Pause einen <a><\/a>11:1-Lauf starten. Halbzeitstand 19:9.<\/p>\n\n\n\n<p>Auch in der zweiten Spielh\u00e4lfte lie\u00dfen unsere Jungs keine Zweifel mehr aufkommen und spielten souver\u00e4n weiter. Doch in der 44. Spielminute bekam die G\u00e4nserndorfer Euphorie einen D\u00e4mpfer. Fl\u00fcgelflitzer Max Zver, gerade erst von einer Verletzung zur\u00fcckgekommen, verdrehte sich bei der Landung nach seinem zehnten Torerfolg des Tages das Knie. Die bittere Diagnose: Kreuzband- und Meniskusriss. Damit ist die Saison f\u00fcr ihn leider gelaufen. Die gesamte UHC-Familie w\u00fcnscht ihm auf diesem Weg nochmals einen guten Heilungsverlauf und viel Kraft f\u00fcr das Comeback. Nach diesem Schock lie\u00df die Konzentration unseres Teams, speziell in der Defensive, etwas nach, am klaren 46:22 Heimerfolg \u00e4nderte das trotzdem nichts mehr.<\/p>\n\n\n\n<p>Nun haben unsere M\u00e4nner zwei Wochen spielfrei, dann geht es am 15.12. ausw\u00e4rts gegen Eggenburg 2 in der Landesliga weiter.<\/p>\n\n\n\n<p>Kader des UHC Schmolengruber G\u00e4nserndorf:<\/p>\n\n\n\n<p>P. Perdoch, J. Stepanovsky (4 Tore), P. Stagl (3), F. M\u00fcller (5), A. Vock (1), M. Zver (10), J. Henzl (2), B. Sch\u00f6nner (8 ), M. Toth (1), S. Dengler (3), P. Freitag (2), M. Billwein (3), D. Wieser, J. Petras (4)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dieses Mal empfing unsere Herrenmannschaft das #1 Team HSV aus Wien. Da die G\u00e4ste stark ersatzgeschw\u00e4cht anreisten ging unser Team als klarer Favorit in die Partie. Zu Beginn war allerdings alles ausgeglichen. Offensiv funktionierte vieles, defensiv eher wenig, so stand es nach 13 gespielten Minuten 8:8. Danach konnte man aber dank einer verbesserten Abwehrleistung und &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/maenner-kantersieg-mit-wermutstropfen\/\"> <span class=\"screen-reader-text\">M\u00e4nner: Kantersieg mit Wermutstropfen<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":6692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,23],"tags":[],"class_list":["post-6691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-herren"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=6691"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6691\/revisions"}],"predecessor-version":[{"id":6693,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6691\/revisions\/6693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/6692"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=6691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=6691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=6691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}