{"id":6649,"date":"2024-11-24T12:16:00","date_gmt":"2024-11-24T11:16:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=6649"},"modified":"2024-11-27T14:17:18","modified_gmt":"2024-11-27T13:17:18","slug":"u11m-klarer-auswaertssieg","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u11m-klarer-auswaertssieg\/","title":{"rendered":"U11M: Klarer Ausw\u00e4rtssieg!"},"content":{"rendered":"\n<p>Die Burschen der u11 feiern ausw\u00e4rts in Baden den zweiten Saisonsieg. Beim letztendlich deutlichen 31:11 Erfolg, ben\u00f6tigten die jungen G\u00e4nserndorfer allerdings 10min um ins Spiel zu kommen. Viele Unkonzentriertheiten pr\u00e4gten das Spiel, wodurch man bis Mitte der ersten Halbzeit einem R\u00fcckstand nachlaufen musste. Mit Fortdauer des Spiels schaffte man es jedoch ins Spiel zu finden. Gegen das schnelle Angriffsspiel der G\u00e4nserndorfer konnten unsere Gegner <a><\/a>nur noch wenig dagegen setzen, wodurch am Ende ein klarer Ausw\u00e4rtserfolg gefeiert werden konnte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Burschen der u11 feiern ausw\u00e4rts in Baden den zweiten Saisonsieg. Beim letztendlich deutlichen 31:11 Erfolg, ben\u00f6tigten die jungen G\u00e4nserndorfer allerdings 10min um ins Spiel zu kommen. Viele Unkonzentriertheiten pr\u00e4gten das Spiel, wodurch man bis Mitte der ersten Halbzeit einem R\u00fcckstand nachlaufen musste. Mit Fortdauer des Spiels schaffte man es jedoch ins Spiel zu finden. &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u11m-klarer-auswaertssieg\/\"> <span class=\"screen-reader-text\">U11M: Klarer Ausw\u00e4rtssieg!<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":6650,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-6649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=6649"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6649\/revisions"}],"predecessor-version":[{"id":6651,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6649\/revisions\/6651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/6650"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=6649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=6649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=6649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}