{"id":6302,"date":"2024-05-25T15:34:00","date_gmt":"2024-05-25T13:34:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=6302"},"modified":"2024-06-03T23:36:17","modified_gmt":"2024-06-03T21:36:17","slug":"u10w-niederlage-gegen-hollabrunn","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u10w-niederlage-gegen-hollabrunn\/","title":{"rendered":"U10W: Niederlage gegen Hollabrunn"},"content":{"rendered":"\n<p>Heute spielten unsere u10 M\u00e4dels ihr letztes Match in dieser Saison gegen den UHC Hollabrunn.<\/p>\n\n\n\n<p>Nach nur wenigen Minuten Spielzeit war der Alters- und der k\u00f6rperliche Unterschied zwischen unseren M\u00e4dels und den G\u00e4sten aus Hollabrunn zu sehen. Die jungen Hollabrunnerinnen gingen von Angang an in F\u00fchrung. Dennoch bem\u00fchten sich unsere M\u00e4dels in der Verteidigung brav hinzugreifen, fingen B\u00e4lle ab und zogen mit sch\u00f6nem Tempo aufs Tor. Trotz hoher Motivation und Spa\u00df am Spiel <a><\/a>musste unsere u10w ihre Saison mit einer -4 Niederlage beenden.<\/p>\n\n\n\n<p>Endstand 10:14 (5:8)<\/p>\n\n\n\n<p><img decoding=\"async\" height=\"16\" width=\"16\" alt=\"\ud83d\udcf8\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/tde\/1\/16\/1f4f8.png\">: Heinz Sattlberger<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute spielten unsere u10 M\u00e4dels ihr letztes Match in dieser Saison gegen den UHC Hollabrunn. Nach nur wenigen Minuten Spielzeit war der Alters- und der k\u00f6rperliche Unterschied zwischen unseren M\u00e4dels und den G\u00e4sten aus Hollabrunn zu sehen. Die jungen Hollabrunnerinnen gingen von Angang an in F\u00fchrung. Dennoch bem\u00fchten sich unsere M\u00e4dels in der Verteidigung brav &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u10w-niederlage-gegen-hollabrunn\/\"> <span class=\"screen-reader-text\">U10W: Niederlage gegen Hollabrunn<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":6303,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-6302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=6302"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6302\/revisions"}],"predecessor-version":[{"id":6304,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6302\/revisions\/6304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/6303"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=6302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=6302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=6302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}