{"id":6103,"date":"2024-03-17T18:10:00","date_gmt":"2024-03-17T17:10:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=6103"},"modified":"2024-03-20T14:11:29","modified_gmt":"2024-03-20T13:11:29","slug":"maenner-heimsieg-gegen-stockerau","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/maenner-heimsieg-gegen-stockerau\/","title":{"rendered":"M\u00e4nner: Heimsieg gegen Stockerau"},"content":{"rendered":"\n<p>Heute empfing unsere M\u00e4nnermannschaft den UHC Stockerau. Das Hinspiel im Herbst hatte man verloren, darum wollten unsere Jungs es diesmal umso besser machen. Aus dem Stammkader fehlte diesmal einzig Maros Vojacek.<\/p>\n\n\n\n<p>Zu Beginn des Spiels gerieten unsere Jungs schnell in R\u00fcckstand, doch lie\u00dfen sich dadurch keineswegs beeindrucken. Nach knapp zehn gespielten Minuten konnte man wieder ausgleichen (6:6) und fortan bestimmten unsere M\u00e4nner das <a><\/a>Spielgeschehen. Nach ungef\u00e4hr 20 Spielminuten f\u00fchrte unser Team dann schon mit 14:8. In dieser Phase konnte man vor Allem in der Deckung \u00fcberzeugen und die gef\u00e4hrlichen R\u00fcckraumwerfer der G\u00e4ste in Schach halten. Bis zur Pause konnten die Stockerauer dann allerdings nochmals etwas aufholen, somit ging unsere Mannschaft mit einer 15:12 Pausenf\u00fchrung in die Kabinen.<\/p>\n\n\n\n<p>In der Pausenansprache wies Coach Michal Fazik eindringlich darauf hin, dass man auf keinen Fall die ersten Minuten der zweiten Spielh\u00e4lfte verschlafen d\u00fcrfe. Spoilerwarnung: genau das Gegenteil passierte. In den ersten f\u00fcnf Minuten der zweiten Halbzeit gelang unserem Team kein einziger Treffer und den G\u00e4sten schlussendlich der Ausgleich. Als dann endlich das erl\u00f6sende erste Tor im zweiten Abschnitt fiel, l\u00f6ste sich auch der Knopf im Spiel unserer Jungs. Auch dank lautstarker Unterst\u00fctzung von der Trib\u00fcne, konnte man sich schnell wieder drei Tore absetzen und diese F\u00fchrung in den n\u00e4chsten Minuten kontinuierlich ausbauen. Zu dem an diesem Tag gut funktionierenden Angriffsspiel gesellte sich immer mehr auch eine stabile Deckung, mit der sich die G\u00e4ste sehr schwertaten. Am Ende spielten unsere Herren den Sieg also doch noch souver\u00e4n nach Hause und gewannen mit 31:25.<\/p>\n\n\n\n<p>N\u00e4chsten Samstag geht es f\u00fcr die M\u00e4nner schon weiter mit dem Heimspiel gegen Eggenburg 2.<\/p>\n\n\n\n<p>Kader des UHC: P. Perdoch, F. Schmid, M. Fazik (1 Tor), F. M\u00fcller, J. Pachowsky (1), F. Weindl, M. Zver (3), J. Henzl (7), B. Sch\u00f6nner (5), M. Toth (4), P. Freitag (3), A. H\u00fcbbe, J. Stepanovsky (7)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute empfing unsere M\u00e4nnermannschaft den UHC Stockerau. Das Hinspiel im Herbst hatte man verloren, darum wollten unsere Jungs es diesmal umso besser machen. Aus dem Stammkader fehlte diesmal einzig Maros Vojacek. Zu Beginn des Spiels gerieten unsere Jungs schnell in R\u00fcckstand, doch lie\u00dfen sich dadurch keineswegs beeindrucken. Nach knapp zehn gespielten Minuten konnte man wieder &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/maenner-heimsieg-gegen-stockerau\/\"> <span class=\"screen-reader-text\">M\u00e4nner: Heimsieg gegen Stockerau<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":6104,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,23],"tags":[],"class_list":["post-6103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-herren"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=6103"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6103\/revisions"}],"predecessor-version":[{"id":6105,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/6103\/revisions\/6105"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/6104"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=6103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=6103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=6103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}