{"id":5901,"date":"2024-02-25T12:59:00","date_gmt":"2024-02-25T11:59:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=5901"},"modified":"2024-02-26T22:00:55","modified_gmt":"2024-02-26T21:00:55","slug":"u11w-sieg-gegen-tulln-2016","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u11w-sieg-gegen-tulln-2016\/","title":{"rendered":"U11W: Sieg gegen Tulln (20:16)"},"content":{"rendered":"\n<p>In der ersten Halbzeit war es aufgrund der Manndeckung ein Hin und Her auf beiden Seiten. Zum Halbzeitpfiff lagen die jungen Handballerinnen aus G\u00e4nserndorf mit zwei Toren zur\u00fcck. In der zweiten Spielh\u00e4lfte wurde aufgrund einer sehr guten Abwehr- und Torfrauleistung in Kombination mit guten W\u00fcrfen im Angriff schlussendlich ein vier Tore Vorsprung erk\u00e4mpft. Besonders hervorzuheben ist, dass es den M\u00e4dels gelungen ist in den <a><\/a>letzten 12 Spielminuten keinen Gegentreffer zu erhalten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der ersten Halbzeit war es aufgrund der Manndeckung ein Hin und Her auf beiden Seiten. Zum Halbzeitpfiff lagen die jungen Handballerinnen aus G\u00e4nserndorf mit zwei Toren zur\u00fcck. In der zweiten Spielh\u00e4lfte wurde aufgrund einer sehr guten Abwehr- und Torfrauleistung in Kombination mit guten W\u00fcrfen im Angriff schlussendlich ein vier Tore Vorsprung erk\u00e4mpft. Besonders hervorzuheben &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u11w-sieg-gegen-tulln-2016\/\"> <span class=\"screen-reader-text\">U11W: Sieg gegen Tulln (20:16)<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":5902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-5901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=5901"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5901\/revisions"}],"predecessor-version":[{"id":5903,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5901\/revisions\/5903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/5902"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=5901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=5901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=5901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}