{"id":5835,"date":"2024-02-03T16:42:00","date_gmt":"2024-02-03T15:42:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=5835"},"modified":"2024-02-13T21:43:57","modified_gmt":"2024-02-13T20:43:57","slug":"maenner-sieg-in-perchtoldsdorf","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/maenner-sieg-in-perchtoldsdorf\/","title":{"rendered":"M\u00e4nner: Sieg in Perchtoldsdorf!"},"content":{"rendered":"\n<p>Unsere M\u00e4nner waren im Rahmen der nieder\u00f6sterreichischen Landesliga ausw\u00e4rts in Perchtoldsdorf zu Gast.<\/p>\n\n\n\n<p>In den ersten Spielminuten wirkte unser Team noch phasenweise zu unmotiviert, nach f\u00fcnf Minuten stand es 3:3, doch nach den ersten beiden Paraden von Tormann Arkadiusz H\u00fcbbe konnte unser Team den Schalter umlegen und gleich mehrere G\u00e4nge hochschalten. In weiterer Folge spielte man eine starke Deckung sowie einen sch\u00f6nen, variantenreichen Angriffshandball, bei dem unseren Jungs fast alles aufging. Zur Pause f\u00fchrte man dann \u00fcberlegen mit 6:21.<\/p>\n\n\n\n<p>Nach der Pause lie\u00df die Deckungsintensit\u00e4t unserer M\u00e4nner allerdings merklich nach. Dadurch kamen die Gastgeber zu einigen leichten Torerfolgen. Der Angriff lief f\u00fcr unsere Jungs zwar weiterhin sehr gut, allerdings fehlten \u00fcber weite Strecken die einfachen Tore durch Gegenst\u00f6\u00dfe, da man fast immer einen Gegentreffer hinnehmen musste. Trotz allem brachte unser Team den Sieg souver\u00e4n nach Hause und setzte sich in Perchtoldsdorf mit 24:41 durch.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unsere M\u00e4nner waren im Rahmen der nieder\u00f6sterreichischen Landesliga ausw\u00e4rts in Perchtoldsdorf zu Gast. In den ersten Spielminuten wirkte unser Team noch phasenweise zu unmotiviert, nach f\u00fcnf Minuten stand es 3:3, doch nach den ersten beiden Paraden von Tormann Arkadiusz H\u00fcbbe konnte unser Team den Schalter umlegen und gleich mehrere G\u00e4nge hochschalten. In weiterer Folge spielte &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/maenner-sieg-in-perchtoldsdorf\/\"> <span class=\"screen-reader-text\">M\u00e4nner: Sieg in Perchtoldsdorf!<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":5836,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,23],"tags":[],"class_list":["post-5835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-herren"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=5835"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5835\/revisions"}],"predecessor-version":[{"id":5837,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5835\/revisions\/5837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/5836"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=5835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=5835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=5835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}