{"id":5308,"date":"2023-10-08T10:31:00","date_gmt":"2023-10-08T08:31:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=5308"},"modified":"2023-10-12T00:33:34","modified_gmt":"2023-10-11T22:33:34","slug":"u18w-starke-erste-halbzeit-wurde-nicht-belohnt","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u18w-starke-erste-halbzeit-wurde-nicht-belohnt\/","title":{"rendered":"U18W: starke erste Halbzeit wurde nicht belohnt"},"content":{"rendered":"\n<p>Heute spielten unsere U18 M\u00e4dels gegen Greenpower JAGS Roomz Wr. Neustadt. Von Beginn an war der Kampfgeist der jungen Mannschaft zu sp\u00fcren, einige Kombinationen konnten treffsicher verwertet werden. Auch die Abwehrleistung war sehr zufriedenstellend, zur Halbzeit stand es verdient 11:10.<\/p>\n\n\n\n<p>In der zweiten H\u00e4lfte gelang der Start nicht so einfach, da auch die Gegnerinnen nachsetzten. Mit nur einer Ersatzspielerin auf der Bank, k\u00e4mpften unsere M\u00e4dels gegen die Schw\u00e4chephase. Letztendlich setzte sich Wr. Neustadt mit 27:16 durch.<br>Wichtig ist, das Positive und den Kampfgeist der ersten Halbzeit\u00a0mitzunehmen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute spielten unsere U18 M\u00e4dels gegen Greenpower JAGS Roomz Wr. Neustadt. Von Beginn an war der Kampfgeist der jungen Mannschaft zu sp\u00fcren, einige Kombinationen konnten treffsicher verwertet werden. Auch die Abwehrleistung war sehr zufriedenstellend, zur Halbzeit stand es verdient 11:10. In der zweiten H\u00e4lfte gelang der Start nicht so einfach, da auch die Gegnerinnen nachsetzten. &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u18w-starke-erste-halbzeit-wurde-nicht-belohnt\/\"> <span class=\"screen-reader-text\">U18W: starke erste Halbzeit wurde nicht belohnt<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":5309,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-5308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=5308"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5308\/revisions"}],"predecessor-version":[{"id":5310,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5308\/revisions\/5310"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/5309"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=5308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=5308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=5308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}