{"id":5305,"date":"2023-10-08T11:28:00","date_gmt":"2023-10-08T09:28:00","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=5305"},"modified":"2023-10-12T00:29:46","modified_gmt":"2023-10-11T22:29:46","slug":"u11m-1-gegen-staerksten-gegner","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u11m-1-gegen-staerksten-gegner\/","title":{"rendered":"U11M: -1 gegen st\u00e4rksten Gegner"},"content":{"rendered":"\n<p>Stark gek\u00e4mpft mit dem Sieg vor Augen mussten sich die Burschen der u11 letztendlich mit 27:26 gegen die vermeintlich st\u00e4rksten Gegner in ihrer Gruppe geschlagen geben.<\/p>\n\n\n\n<p>Ein Spiel in M\u00f6dling mit einem Tor Unterschied zu verlieren ist extrem bitter. Da f\u00fcr die Mannschaft aber die Entwicklungen jedes Einzelnen sowie des gesamten Teams im Vordergrund stehen, kann das Spiel moralisch wie ein Sieg gewertet werden. Vorallem wenn man daran denkt Mitte der zweiten Halbzeit mit 4 Toren <a><\/a>gef\u00fchrt zu haben, ist das Potenzial der Burschen mehr als erkennbar. Abermals war es die Mannschaftsleistung, die der Schl\u00fcssel zum tollen Spiel war. Jeder Feldspieler konnte sich in die Torsch\u00fctzenliste eintragen. Zudem konnte Simon Scheidl im Tor eine seiner besten Leistungen seiner bisherigen Karriere abrufen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Stark gek\u00e4mpft mit dem Sieg vor Augen mussten sich die Burschen der u11 letztendlich mit 27:26 gegen die vermeintlich st\u00e4rksten Gegner in ihrer Gruppe geschlagen geben. Ein Spiel in M\u00f6dling mit einem Tor Unterschied zu verlieren ist extrem bitter. Da f\u00fcr die Mannschaft aber die Entwicklungen jedes Einzelnen sowie des gesamten Teams im Vordergrund stehen, &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u11m-1-gegen-staerksten-gegner\/\"> <span class=\"screen-reader-text\">U11M: -1 gegen st\u00e4rksten Gegner<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":5306,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-5305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=5305"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5305\/revisions"}],"predecessor-version":[{"id":5307,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5305\/revisions\/5307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/5306"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=5305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=5305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=5305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}