{"id":5294,"date":"2023-10-07T17:52:00","date_gmt":"2023-10-07T15:52:00","guid":{"rendered":"http:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=5294"},"modified":"2023-10-08T23:59:40","modified_gmt":"2023-10-08T21:59:40","slug":"u14m-verdienter-sieg-gegen-handball-woelfe-wien","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u14m-verdienter-sieg-gegen-handball-woelfe-wien\/","title":{"rendered":"U14M: Verdienter Sieg gegen Handball W\u00f6lfe Wien"},"content":{"rendered":"\n<p>Heute spielten unsere Burschen der U14 im Elite-Cup gegen die Handball W\u00f6lfe Wien.<br>Trotz einiger Ausf\u00e4lle &amp; mit nur einem Auswechselspieler gingen die Jungs motiviert in das Spiel. Unter den Ausf\u00e4llen war auch Trainer Armin Schmoldas, gecoacht wurde die Mannschaft daher von Jo Henzl &amp; Kati Freitag.<\/p>\n\n\n\n<p>Zu Beginn hatten unsere Burschen Probleme, ins Spiel zu finden. Dank&#8217; einem guten Felix Schmolengruber im Tor konnten sich die Gegner jedoch nicht absetzen &amp; nach 12 Minuten ging unsere U14 das erste Mal &#8211; durch Valentin Prager &#8211; 8:7 in F\u00fchrung.<br>Ab dann wurden die G\u00e4nserndorfer allerdings unruhig, technische Fehler verhinderten einen Ausbau der F\u00fchrung &amp; die W\u00f6lfe hatten zur Halbzeit einen 13:15 Vorsprung.<\/p>\n\n\n\n<p>Auch der Beginn der zweiten Halbzeit entwickelte sich nicht wie gew\u00fcnscht. Die gegnerischen Jungs konnten in k\u00fcrzester Zeit 4 Tore hintereinander erzielen, f\u00fchrten 14:19.<br>Unsere Burschen lie\u00dfen die K\u00f6pfe jedoch nicht h\u00e4ngen, nach taktischen Anweisungen des Trainerteams k\u00e4mpften sie sich im Laufe der zweiten H\u00e4lfte zur\u00fcck &amp; konnten den Spielstand drehen, Endstand&nbsp;28:26!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Heute spielten unsere Burschen der U14 im Elite-Cup gegen die Handball W\u00f6lfe Wien.Trotz einiger Ausf\u00e4lle &amp; mit nur einem Auswechselspieler gingen die Jungs motiviert in das Spiel. Unter den Ausf\u00e4llen war auch Trainer Armin Schmoldas, gecoacht wurde die Mannschaft daher von Jo Henzl &amp; Kati Freitag. Zu Beginn hatten unsere Burschen Probleme, ins Spiel zu &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u14m-verdienter-sieg-gegen-handball-woelfe-wien\/\"> <span class=\"screen-reader-text\">U14M: Verdienter Sieg gegen Handball W\u00f6lfe Wien<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":5295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-5294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=5294"}],"version-history":[{"count":2,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5294\/revisions"}],"predecessor-version":[{"id":5300,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5294\/revisions\/5300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/5295"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=5294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=5294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=5294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}