{"id":5169,"date":"2023-09-30T12:17:00","date_gmt":"2023-09-30T10:17:00","guid":{"rendered":"http:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=5169"},"modified":"2023-10-04T21:19:56","modified_gmt":"2023-10-04T19:19:56","slug":"u11w-unentschieden-gegen-st-poelten","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u11w-unentschieden-gegen-st-poelten\/","title":{"rendered":"U11W: Unentschieden gegen St. P\u00f6lten!"},"content":{"rendered":"\n<p>Die Spielerinnen der U11 bestritten ihr erstes Meisterschaftsspiel in St. P\u00f6lten. Nach kurzer Spielzeit lag das Team mit 3:9 hinten. Durch einen tollen Kampfgeist konnte zur Halbzeit auf 10:10 gestellt werden. In der 2. Spielh\u00e4lfte war das Match sehr ausgeglichen. Durch einen Schlagwurf ins Kreuzeck vier Sekunden vor Spielende konnte ein verdienter Punkt aus unserer Landeshauptstadt mitgenommen werden (19:19). Die sportliche Leistung des gesamten Teams (erstmals trugen sich 6 Spielerinnen des UHC in die Torsch\u00fctzenliste ein) war\u00a0bemerkenswert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Spielerinnen der U11 bestritten ihr erstes Meisterschaftsspiel in St. P\u00f6lten. Nach kurzer Spielzeit lag das Team mit 3:9 hinten. Durch einen tollen Kampfgeist konnte zur Halbzeit auf 10:10 gestellt werden. In der 2. Spielh\u00e4lfte war das Match sehr ausgeglichen. Durch einen Schlagwurf ins Kreuzeck vier Sekunden vor Spielende konnte ein verdienter Punkt aus unserer &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u11w-unentschieden-gegen-st-poelten\/\"> <span class=\"screen-reader-text\">U11W: Unentschieden gegen St. P\u00f6lten!<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":5,"featured_media":5170,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-5169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=5169"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5169\/revisions"}],"predecessor-version":[{"id":5171,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/5169\/revisions\/5171"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/5170"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=5169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=5169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=5169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}