{"id":4024,"date":"2023-03-12T17:52:28","date_gmt":"2023-03-12T16:52:28","guid":{"rendered":"http:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=4024"},"modified":"2023-04-08T12:02:23","modified_gmt":"2023-04-08T10:02:23","slug":"u10-burschen-kantersieg-gegen-perchtoldsdorf","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u10-burschen-kantersieg-gegen-perchtoldsdorf\/","title":{"rendered":"U10 Burschen &#8211; Kantersieg gegen Perchtoldsdorf"},"content":{"rendered":"\n<p>Am Sonntag haben die Burschen der u10 ihr zweites Spiel im Playoff bestritten. Obwohl ersatzgeschw\u00e4cht mit nur einem Wechselspieler konnten die jungen G\u00e4nserndorfer ihr K\u00f6nnen unter Beweis stellen und einen ungef\u00e4hrdeten Kantersieg mit 39:2 gegen die Alterskollegen aus Perchtoldsdorf einfahren. Sch\u00f6nes Passspiel und viele Kontertore waren der Schl\u00fcssel zum Erfolg. Mit zwei Siegen aus zwei Spielen liegt G\u00e4nserndorf auf dem ersten Platz in der Tabelle. Kommende Woche wartet im Weinviertelderby mit Stockerau ein ebenb\u00fcrtiger Gegner, der Simon Scheidl und Co vermutlich mehr fordern wird.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Sonntag haben die Burschen der u10 ihr zweites Spiel im Playoff bestritten. Obwohl ersatzgeschw\u00e4cht mit nur einem Wechselspieler konnten die jungen G\u00e4nserndorfer ihr K\u00f6nnen unter Beweis stellen und einen ungef\u00e4hrdeten Kantersieg mit 39:2 gegen die Alterskollegen aus Perchtoldsdorf einfahren. Sch\u00f6nes Passspiel und viele Kontertore waren der Schl\u00fcssel zum Erfolg. Mit zwei Siegen aus zwei &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u10-burschen-kantersieg-gegen-perchtoldsdorf\/\"> <span class=\"screen-reader-text\">U10 Burschen &#8211; Kantersieg gegen Perchtoldsdorf<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":6,"featured_media":4025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[1,24],"tags":[],"class_list":["post-4024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/4024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=4024"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/4024\/revisions"}],"predecessor-version":[{"id":4026,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/4024\/revisions\/4026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/4025"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=4024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=4024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=4024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}