{"id":3859,"date":"2023-02-18T19:09:52","date_gmt":"2023-02-18T18:09:52","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=3859"},"modified":"2023-02-22T19:20:14","modified_gmt":"2023-02-22T18:20:14","slug":"uhc-herren-verpassen-sieg","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/uhc-herren-verpassen-sieg\/","title":{"rendered":"UHC Herren verpassen Sieg"},"content":{"rendered":"\n<p>Vergangenen Samstag, 18.02.2023 empfing unsere M\u00e4nnermannschaft die Regionalligamannschaft von West Wien.<\/p>\n\n\n\n<p>In der Anfangsphase war das Spiel erwartungsgem\u00e4\u00df eng, doch nach knapp 15 Minuten konnte sich G\u00e4nserndorf das erste mal eine 3-Tore-F\u00fchrung herausspielen. In weiterer Folge tat sich unser Team dann allerdings in der Offensive sehr schwer und so konnten die G\u00e4ste den R\u00fcckstand wieder wettmachen und lagen zur Pause mit einem Tor voran.<\/p>\n\n\n\n<p>Die zweite Halbzeit war beinahe ein Spiegelbild der <a><\/a>ersten. Zu Beginn spielten beide Mannschaften auf Augenh\u00f6he, doch im Laufe des Spiels konnte sich unser Team erneut etwas absetzen. Knapp 10 Minuten vor Spielende f\u00fchrte man dann mit 4 Toren, jedoch verlief ab diesem Zeitpunkt nicht mehr viel nach Wunsch. So konnten die Wiener erneut ausgleichen und hatten in der letzten Spielminute sogar die Chance in F\u00fchrung zu gehen, doch eine starke G\u00e4nserndorfer Deckung wusste das zu verhindern.<\/p>\n\n\n\n<p>Am Ende blieb es beim 26:26, mit dem die Mannschaft von West Wien an diesem Tag wahrscheinlich besser leben kann.<\/p>\n\n\n\n<p>Wir bedanken uns bei RE\/MAX Eco G\u00e4nserndorf f\u00fcr die \u00dcbernahme der Matchpatronanz und Tombola an jenem Tag!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vergangenen Samstag, 18.02.2023 empfing unsere M\u00e4nnermannschaft die Regionalligamannschaft von West Wien. In der Anfangsphase war das Spiel erwartungsgem\u00e4\u00df eng, doch nach knapp 15 Minuten konnte sich G\u00e4nserndorf das erste mal eine 3-Tore-F\u00fchrung herausspielen. In weiterer Folge tat sich unser Team dann allerdings in der Offensive sehr schwer und so konnten die G\u00e4ste den R\u00fcckstand wieder &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/uhc-herren-verpassen-sieg\/\"> <span class=\"screen-reader-text\">UHC Herren verpassen Sieg<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":4,"featured_media":3860,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-3859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-herren"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/3859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=3859"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/3859\/revisions"}],"predecessor-version":[{"id":3861,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/3859\/revisions\/3861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/3860"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=3859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=3859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=3859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}