{"id":3185,"date":"2022-11-19T20:33:44","date_gmt":"2022-11-19T19:33:44","guid":{"rendered":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/?p=3185"},"modified":"2022-11-29T20:34:01","modified_gmt":"2022-11-29T19:34:01","slug":"u16-jungs-mussten-sich-wat-fuenfhaus-geschlagen-geben","status":"publish","type":"post","link":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u16-jungs-mussten-sich-wat-fuenfhaus-geschlagen-geben\/","title":{"rendered":"U16 Jungs mussten sich WAT F\u00fcnfhaus geschlagen geben"},"content":{"rendered":"\n<p>Die Jungs der U16 spielten Samstag, 19. November zur Mittagszeit ihr erstes Heimspiel gegen WAT F\u00fcnfhaus. <\/p>\n\n\n\n<p>Die Wiener spielen einen guten Tempohandball, der uns anfangs \u00fcberraschte &#8211; wir lagen bereits nach 12 Minuten 2:10 im R\u00fcckstand. In der Folge fanden wir besser ins Spiel, vor allem im Angriff wurden immer wieder sch\u00f6ne Tore erzielt. <\/p>\n\n\n\n<p>Leider starteten wir auch in die 2. H\u00e4lfte unkonzentriert. Viele unserer technischen Fehler f\u00fchrten zu Gegensto\u00dftoren, obwohl sich Dario im Tor immer wieder auszeichnen konnte. Leider war unser Fl\u00fcgelspiel an diesem Tag nicht sehr effizient, wir konnten aus einer Vielzahl von Chancen, gegen den gro\u00dfgewachsenen Tormann, nicht oft erfolgreich sein. Positiv ist es, dass wir einige Tore aus der 2. Reihe erzielen konnten &#8211; Felix G\u00f6tz stieg ein paar mal gut auf, Leonhard war mit Schlagwurfvarianten erfolgreich und Valentin nutzte seine Schnelligkeit aus. <\/p>\n\n\n\n<p>So endete die Partie UHC Raiffeisenbank G\u00e4nserndorf &#8211; WAT F\u00fcnfhaus Handball leider nur 18:41.<br>Alles in allem immer wieder gute Phasen, etwas zuviele Ballverluste, und Schlampigkeiten verhinderten ein besseres Resultat &#8211; aber ein sch\u00f6nes Spiel!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Jungs der U16 spielten Samstag, 19. November zur Mittagszeit ihr erstes Heimspiel gegen WAT F\u00fcnfhaus. Die Wiener spielen einen guten Tempohandball, der uns anfangs \u00fcberraschte &#8211; wir lagen bereits nach 12 Minuten 2:10 im R\u00fcckstand. In der Folge fanden wir besser ins Spiel, vor allem im Angriff wurden immer wieder sch\u00f6ne Tore erzielt. Leider &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/u16-jungs-mussten-sich-wat-fuenfhaus-geschlagen-geben\/\"> <span class=\"screen-reader-text\">U16 Jungs mussten sich WAT F\u00fcnfhaus geschlagen geben<\/span> Weiterlesen &raquo;<\/a><\/p>\n","protected":false},"author":4,"featured_media":3186,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"categories":[24],"tags":[],"class_list":["post-3185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jugend"],"_links":{"self":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/3185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/comments?post=3185"}],"version-history":[{"count":1,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/3185\/revisions"}],"predecessor-version":[{"id":3187,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/posts\/3185\/revisions\/3187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media\/3186"}],"wp:attachment":[{"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/media?parent=3185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/categories?post=3185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uhc-gaenserndorf.com\/wp-uhc\/wp-json\/wp\/v2\/tags?post=3185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}